{"id":9096,"date":"2023-03-22T11:57:01","date_gmt":"2023-03-22T15:57:01","guid":{"rendered":"https:\/\/noht-eson.ca\/?p=9096"},"modified":"2023-04-13T15:21:44","modified_gmt":"2023-04-13T19:21:44","slug":"la-noht%e2%80%91eson-lance-lexplorateur-de-ressources","status":"publish","type":"post","link":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/","title":{"rendered":"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources"},"content":{"rendered":"<p><strong><img decoding=\"async\" class=\"size-medium wp-image-9097 alignright\" src=\"https:\/\/noht-eson.ca\/wp-content\/uploads\/\/Resource-Navigator-Instagram-1-FR-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR-300x300.jpg 300w, https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR-1030x1030.jpg 1030w, https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR-80x80.jpg 80w, https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR-768x768.jpg 768w, https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR-36x36.jpg 36w, https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR-180x180.jpg 180w, https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR-705x705.jpg 705w, https:\/\/noht-eson.ca\/wp-content\/uploads\/Resource-Navigator-Instagram-1-FR.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>St.<\/strong>\u00a0<strong>Catharines, ON<\/strong> \u2013 Les r\u00e9sidents de la r\u00e9gion de Niagara disposent d\u2019un nouvel outil en ligne pour trouver des services de soins de sant\u00e9 et des services sociaux locaux et provinciaux offerts dans la r\u00e9gion. La page Web de l\u2019Explorateur de ressources a \u00e9t\u00e9 lanc\u00e9e aujourd\u2019hui. L\u2019outil se compose de plusieurs cat\u00e9gories qui permettent aux gens de trouver rapidement les services dont ils ont besoin, 24\u00a0heures sur\u00a024, 7\u00a0jours sur\u00a07.<\/p>\n<p>\u00ab\u00a0Nous savons que les gens ont souvent du mal \u00e0 trouver les soins appropri\u00e9s dont ils ont besoin, en particulier lorsqu\u2019ils traversent une p\u00e9riode difficile ou qu\u2019ils sont en situation de crise. Parfois, les organismes et les professionnels de la sant\u00e9 ne sont pas au courant des services qui existent dans la communaut\u00e9 et qui pourraient \u00eatre utiles \u00e0 leurs patients ou \u00e0 leurs clients\u00a0\u00bb, a indiqu\u00e9 Sabrina\u00a0Piluso, directrice de la planification pour la Niagara Ontario Health Team \u2013 \u00c9quipe Sant\u00e9 Ontario Niagara\u00a0(NOHT\u2011\u00c9SON).<\/p>\n<p>\u00ab\u00a0En facilitant l\u2019acc\u00e8s \u00e0 l\u2019information gr\u00e2ce \u00e0 l\u2019Explorateur de ressources, nous esp\u00e9rons am\u00e9liorer les r\u00e9sultats et les exp\u00e9riences en mati\u00e8re de sant\u00e9 des r\u00e9sidents de la r\u00e9gion de Niagara.\u00a0\u00bb<\/p>\n<p>L\u2019\u00e9quipe du projet de Navigation\u00a024\/7 a men\u00e9 des d\u00e9marches d\u2019envergure aupr\u00e8s des patients, des clients, des familles, des soignants et des groupes communautaires de la r\u00e9gion afin de relever les services de soins de sant\u00e9 et les services sociaux existants. Les renseignements sont pr\u00e9sent\u00e9s d\u2019une mani\u00e8re adapt\u00e9e aux besoins de la personne.<\/p>\n<p>Parmi les cat\u00e9gories r\u00e9pertori\u00e9es sur le site <a href=\"https:\/\/noht-eson.ca\/fr\/explorateur-de-ressources\">https:\/\/noht-eson.ca\/fr\/explorateur-de-ressources<\/a>, nous retrouvons le soutien en cas d\u2019urgence et\/ou de crise, les services de sant\u00e9 \u00e0 domicile et de soutien communautaire, les services en lien avec la sant\u00e9 des Autochtones et leurs communaut\u00e9s, les services de sant\u00e9 et communautaires en fran\u00e7ais et les services de soins pour les a\u00een\u00e9s.<\/p>\n<p>\u00ab\u00a0Si je suis un nouvel arrivant, une personne francophone ou un soignant, j\u2019ai acc\u00e8s \u00e0 diff\u00e9rents parcours pour trouver l\u2019aide dont j\u2019ai besoin\u00a0\u00bb, a ajout\u00e9 M<sup>me<\/sup>\u00a0Piluso.<\/p>\n<p>\u00ab\u00a0De m\u00eame, je peux trouver des services de mani\u00e8re proactive, quel que soit le point o\u00f9 je me situe dans mon parcours de soins de sant\u00e9, et je peux \u00e9viter que ce qui me pr\u00e9occupe ne devienne une crise. L\u2019Explorateur de ressources fournit des renseignements de mani\u00e8re pratique et coordonn\u00e9e, permettant aux gens d\u2019\u00eatre au c\u0153ur de la prise de d\u00e9cisions concernant leur sant\u00e9 et leur bien\u2011\u00eatre.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>St.\u00a0Catharines, ON \u2013 Les r\u00e9sidents de la r\u00e9gion de Niagara disposent d\u2019un nouvel outil en ligne pour trouver des services de soins de sant\u00e9 et des services sociaux locaux et provinciaux offerts dans la r\u00e9gion. La page Web de l\u2019Explorateur de ressources a \u00e9t\u00e9 lanc\u00e9e aujourd\u2019hui. L\u2019outil se compose de plusieurs cat\u00e9gories qui permettent aux [&hellip;]<\/p>\n","protected":false},"author":94,"featured_media":9073,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[44,59],"tags":[],"class_list":["post-9096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mises-a-jour","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noht-eson.ca\/fr\/la-noht\u2011eson-lance-lexplorateur-de-ressources\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\" \/>\n<meta property=\"og:description\" content=\"St.\u00a0Catharines, ON \u2013 Les r\u00e9sidents de la r\u00e9gion de Niagara disposent d\u2019un nouvel outil en ligne pour trouver des services de soins de sant\u00e9 et des services sociaux locaux et provinciaux offerts dans la r\u00e9gion. La page Web de l\u2019Explorateur de ressources a \u00e9t\u00e9 lanc\u00e9e aujourd\u2019hui. L\u2019outil se compose de plusieurs cat\u00e9gories qui permettent aux [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noht-eson.ca\/fr\/la-noht\u2011eson-lance-lexplorateur-de-ressources\/\" \/>\n<meta property=\"og:site_name\" content=\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/NiagaraOHT\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-22T15:57:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-13T19:21:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/noht-eson.ca\/wp-content\/uploads\/Resouce-Navigator-Instagran-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ron Laroche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@niagaraoht\" \/>\n<meta name=\"twitter:site\" content=\"@niagaraoht\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ron Laroche\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/\"},\"author\":{\"name\":\"Ron Laroche\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#\\\/schema\\\/person\\\/79b025e6edbf2d5399452e8ba2a6ac63\"},\"headline\":\"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources\",\"datePublished\":\"2023-03-22T15:57:01+00:00\",\"dateModified\":\"2023-04-13T19:21:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/\"},\"wordCount\":449,\"publisher\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/Resouce-Navigator-Instagran-2.jpg\",\"articleSection\":[\"Mises \u00e0 jour\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/\",\"name\":\"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/Resouce-Navigator-Instagran-2.jpg\",\"datePublished\":\"2023-03-22T15:57:01+00:00\",\"dateModified\":\"2023-04-13T19:21:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/#primaryimage\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/Resouce-Navigator-Instagran-2.jpg\",\"contentUrl\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/Resouce-Navigator-Instagran-2.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#website\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/\",\"name\":\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\",\"description\":\"Exceptional, connected care, now and for future generations\",\"publisher\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noht-eson.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#organization\",\"name\":\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/NOHT_ESON_Logo_FINAL-1.jpg\",\"contentUrl\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/NOHT_ESON_Logo_FINAL-1.jpg\",\"width\":1500,\"height\":500,\"caption\":\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\"},\"image\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/NiagaraOHT\\\/\",\"https:\\\/\\\/x.com\\\/niagaraoht\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#\\\/schema\\\/person\\\/79b025e6edbf2d5399452e8ba2a6ac63\",\"name\":\"Ron Laroche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b59d3ade3ae68948ff3f7b5992bdf1a9f2ed7dd94725a87a90fb0cb4819973a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b59d3ade3ae68948ff3f7b5992bdf1a9f2ed7dd94725a87a90fb0cb4819973a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b59d3ade3ae68948ff3f7b5992bdf1a9f2ed7dd94725a87a90fb0cb4819973a?s=96&d=mm&r=g\",\"caption\":\"Ron Laroche\"},\"url\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/author\\\/communications\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noht-eson.ca\/fr\/la-noht\u2011eson-lance-lexplorateur-de-ressources\/","og_locale":"fr_FR","og_type":"article","og_title":"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","og_description":"St.\u00a0Catharines, ON \u2013 Les r\u00e9sidents de la r\u00e9gion de Niagara disposent d\u2019un nouvel outil en ligne pour trouver des services de soins de sant\u00e9 et des services sociaux locaux et provinciaux offerts dans la r\u00e9gion. La page Web de l\u2019Explorateur de ressources a \u00e9t\u00e9 lanc\u00e9e aujourd\u2019hui. L\u2019outil se compose de plusieurs cat\u00e9gories qui permettent aux [&hellip;]","og_url":"https:\/\/noht-eson.ca\/fr\/la-noht\u2011eson-lance-lexplorateur-de-ressources\/","og_site_name":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","article_publisher":"https:\/\/facebook.com\/NiagaraOHT\/","article_published_time":"2023-03-22T15:57:01+00:00","article_modified_time":"2023-04-13T19:21:44+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/noht-eson.ca\/wp-content\/uploads\/Resouce-Navigator-Instagran-2.jpg","type":"image\/jpeg"}],"author":"Ron Laroche","twitter_card":"summary_large_image","twitter_creator":"@niagaraoht","twitter_site":"@niagaraoht","twitter_misc":{"\u00c9crit par":"Ron Laroche","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/#article","isPartOf":{"@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/"},"author":{"name":"Ron Laroche","@id":"https:\/\/noht-eson.ca\/#\/schema\/person\/79b025e6edbf2d5399452e8ba2a6ac63"},"headline":"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources","datePublished":"2023-03-22T15:57:01+00:00","dateModified":"2023-04-13T19:21:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/"},"wordCount":449,"publisher":{"@id":"https:\/\/noht-eson.ca\/#organization"},"image":{"@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/#primaryimage"},"thumbnailUrl":"https:\/\/noht-eson.ca\/wp-content\/uploads\/Resouce-Navigator-Instagran-2.jpg","articleSection":["Mises \u00e0 jour","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/","url":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/","name":"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","isPartOf":{"@id":"https:\/\/noht-eson.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/#primaryimage"},"image":{"@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/#primaryimage"},"thumbnailUrl":"https:\/\/noht-eson.ca\/wp-content\/uploads\/Resouce-Navigator-Instagran-2.jpg","datePublished":"2023-03-22T15:57:01+00:00","dateModified":"2023-04-13T19:21:44+00:00","breadcrumb":{"@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/#primaryimage","url":"https:\/\/noht-eson.ca\/wp-content\/uploads\/Resouce-Navigator-Instagran-2.jpg","contentUrl":"https:\/\/noht-eson.ca\/wp-content\/uploads\/Resouce-Navigator-Instagran-2.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/noht-eson.ca\/fr\/la-noht%e2%80%91eson-lance-lexplorateur-de-ressources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noht-eson.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"La\u00a0NOHT\u2011\u00c9SON lance l\u2019Explorateur de ressources"}]},{"@type":"WebSite","@id":"https:\/\/noht-eson.ca\/#website","url":"https:\/\/noht-eson.ca\/","name":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","description":"Exceptional, connected care, now and for future generations","publisher":{"@id":"https:\/\/noht-eson.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noht-eson.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/noht-eson.ca\/#organization","name":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","url":"https:\/\/noht-eson.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/noht-eson.ca\/#\/schema\/logo\/image\/","url":"https:\/\/noht-eson.ca\/wp-content\/uploads\/NOHT_ESON_Logo_FINAL-1.jpg","contentUrl":"https:\/\/noht-eson.ca\/wp-content\/uploads\/NOHT_ESON_Logo_FINAL-1.jpg","width":1500,"height":500,"caption":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara"},"image":{"@id":"https:\/\/noht-eson.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/NiagaraOHT\/","https:\/\/x.com\/niagaraoht"]},{"@type":"Person","@id":"https:\/\/noht-eson.ca\/#\/schema\/person\/79b025e6edbf2d5399452e8ba2a6ac63","name":"Ron Laroche","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b59d3ade3ae68948ff3f7b5992bdf1a9f2ed7dd94725a87a90fb0cb4819973a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b59d3ade3ae68948ff3f7b5992bdf1a9f2ed7dd94725a87a90fb0cb4819973a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b59d3ade3ae68948ff3f7b5992bdf1a9f2ed7dd94725a87a90fb0cb4819973a?s=96&d=mm&r=g","caption":"Ron Laroche"},"url":"https:\/\/noht-eson.ca\/fr\/author\/communications\/"}]}},"_links":{"self":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/posts\/9096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/users\/94"}],"replies":[{"embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/comments?post=9096"}],"version-history":[{"count":3,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/posts\/9096\/revisions"}],"predecessor-version":[{"id":9241,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/posts\/9096\/revisions\/9241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/media\/9073"}],"wp:attachment":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/media?parent=9096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/categories?post=9096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/tags?post=9096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}