{"id":12307,"date":"2024-05-03T12:16:31","date_gmt":"2024-05-03T16:16:31","guid":{"rendered":"https:\/\/noht-eson.ca\/?post_type=mec-events&#038;p=12307"},"modified":"2024-05-03T12:16:31","modified_gmt":"2024-05-03T16:16:31","slug":"caravane-de-depistage-mobile-du-cancer-fort-erie-14","status":"publish","type":"mec-events","link":"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/","title":{"rendered":"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie"},"content":{"rendered":"<p>Visitez la caravane de d\u00e9pistage mobile du cancer du Programme r\u00e9gional de canc\u00e9rologie de Hamilton Niagara Haldimand Brant pour b\u00e9n\u00e9ficier de d\u00e9pistages gratuits du cancer du sein, du col de l\u2019ut\u00e9rus et du colon, et de l\u2019aide pour arr\u00eater de fumer. Les places sont limit\u00e9es. Pour prendre rendez-vous, composez le 905-975-4467 ou le num\u00e9ro sans frais 1-855-338-3131.<\/p>\n<p>Cliquez\u00a0<a class=\"lightbox-added\" href=\"https:\/\/noht-eson.ca\/wp-content\/uploads\/Mobile-Cancer-Screening-Coach-May-2024-1.png\" target=\"_blank\" rel=\"noopener\"><strong>ici<\/strong><\/a>\u00a0pour consulter le calendrier et voir o\u00f9 le car mobile de d\u00e9pistage du cancer se rendra la prochaine fois ou visitez le<a href=\"https:\/\/hnhbscreenforlife.ca\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00a0site web<\/strong><\/a>\u00a0pour plus d\u2019informations.<\/p>\n<p>Veuillez noter que la caravane de d\u00e9pistage mobile du cancer est \u00e9quip\u00e9 d\u2019un ascenseur pour fauteuils roulants \u00e0 l\u2019intention des personnes qui ne peuvent pas emprunter les escaliers. Cependant, une fois dans la caravane mobile, une certaine mobilit\u00e9 est n\u00e9cessaire pour acc\u00e9der aux salles de d\u00e9pistage, car celles-ci ne sont pas assez grandes pour certains fauteuils roulants. Veuillez appeler la caravane mobile et demander \u00e0 parler \u00e0 une infirmi\u00e8re pour \u00e9valuer vos besoins sp\u00e9cifiques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visitez la caravane de d\u00e9pistage mobile du cancer du Programme r\u00e9gional de canc\u00e9rologie de Hamilton Niagara Haldimand Brant pour b\u00e9n\u00e9ficier de d\u00e9pistages gratuits du cancer du sein, du col de l\u2019ut\u00e9rus et du colon, et de l\u2019aide pour arr\u00eater de fumer. Les places sont limit\u00e9es. Pour prendre rendez-vous, composez le 905-975-4467 ou le num\u00e9ro sans [&hellip;]<\/p>\n","protected":false},"author":94,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[],"class_list":["post-12307","mec-events","type-mec-events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\" \/>\n<meta property=\"og:description\" content=\"Visitez la caravane de d\u00e9pistage mobile du cancer du Programme r\u00e9gional de canc\u00e9rologie de Hamilton Niagara Haldimand Brant pour b\u00e9n\u00e9ficier de d\u00e9pistages gratuits du cancer du sein, du col de l\u2019ut\u00e9rus et du colon, et de l\u2019aide pour arr\u00eater de fumer. Les places sont limit\u00e9es. Pour prendre rendez-vous, composez le 905-975-4467 ou le num\u00e9ro sans [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/NiagaraOHT\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@niagaraoht\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/events-archive\\\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\\\/\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/events-archive\\\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\\\/\",\"name\":\"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#website\"},\"datePublished\":\"2024-05-03T16:16:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/events-archive\\\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/events-archive\\\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/events-archive\\\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/noht-eson.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/noht-eson.ca\\\/events-archive\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#website\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/\",\"name\":\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\",\"description\":\"Exceptional, connected care, now and for future generations\",\"publisher\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/noht-eson.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#organization\",\"name\":\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/NOHT_ESON_Logo_FINAL-1.jpg\",\"contentUrl\":\"https:\\\/\\\/noht-eson.ca\\\/wp-content\\\/uploads\\\/NOHT_ESON_Logo_FINAL-1.jpg\",\"width\":1500,\"height\":500,\"caption\":\"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara\"},\"image\":{\"@id\":\"https:\\\/\\\/noht-eson.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/NiagaraOHT\\\/\",\"https:\\\/\\\/x.com\\\/niagaraoht\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","og_description":"Visitez la caravane de d\u00e9pistage mobile du cancer du Programme r\u00e9gional de canc\u00e9rologie de Hamilton Niagara Haldimand Brant pour b\u00e9n\u00e9ficier de d\u00e9pistages gratuits du cancer du sein, du col de l\u2019ut\u00e9rus et du colon, et de l\u2019aide pour arr\u00eater de fumer. Les places sont limit\u00e9es. Pour prendre rendez-vous, composez le 905-975-4467 ou le num\u00e9ro sans [&hellip;]","og_url":"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/","og_site_name":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","article_publisher":"https:\/\/facebook.com\/NiagaraOHT\/","twitter_card":"summary_large_image","twitter_site":"@niagaraoht","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/","url":"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/","name":"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie - Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","isPartOf":{"@id":"https:\/\/noht-eson.ca\/#website"},"datePublished":"2024-05-03T16:16:31+00:00","breadcrumb":{"@id":"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noht-eson.ca\/fr\/events-archive\/caravane-de-depistage-mobile-du-cancer-fort-erie-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noht-eson.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/noht-eson.ca\/events-archive\/"},{"@type":"ListItem","position":3,"name":"Caravane de d\u00e9pistage mobile du cancer \u2013 Fort Erie"}]},{"@type":"WebSite","@id":"https:\/\/noht-eson.ca\/#website","url":"https:\/\/noht-eson.ca\/","name":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","description":"Exceptional, connected care, now and for future generations","publisher":{"@id":"https:\/\/noht-eson.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noht-eson.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/noht-eson.ca\/#organization","name":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara","url":"https:\/\/noht-eson.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/noht-eson.ca\/#\/schema\/logo\/image\/","url":"https:\/\/noht-eson.ca\/wp-content\/uploads\/NOHT_ESON_Logo_FINAL-1.jpg","contentUrl":"https:\/\/noht-eson.ca\/wp-content\/uploads\/NOHT_ESON_Logo_FINAL-1.jpg","width":1500,"height":500,"caption":"Niagara Ontario Health Team - \u00c9quipe Sant\u00e9 Ontario Niagara"},"image":{"@id":"https:\/\/noht-eson.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/NiagaraOHT\/","https:\/\/x.com\/niagaraoht"]}]}},"_links":{"self":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/mec-events\/12307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/users\/94"}],"replies":[{"embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/comments?post=12307"}],"wp:attachment":[{"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/media?parent=12307"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/tags?post=12307"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/noht-eson.ca\/fr\/wp-json\/wp\/v2\/mec_category?post=12307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}